{"id":6094,"date":"2023-07-17T12:10:47","date_gmt":"2023-07-17T17:10:47","guid":{"rendered":"https:\/\/importacionesflorida.com\/product\/sensor-eje-levas-atos-to-getz-sta-fe-css-38050-2\/"},"modified":"2026-08-24T18:52:20","modified_gmt":"2026-08-24T23:52:20","slug":"sensor-eje-levas-atos-to-getz-sta-fe-css-38050-2","status":"publish","type":"product","link":"https:\/\/importacionesflorida.com\/es_es\/producto\/sensor-eje-levas-atos-to-getz-sta-fe-css-38050-2\/","title":{"rendered":"SENSOR EJE LEVASAS ATOS TODOS \/ GETZ \/ SANTA FE (CSS-38050-2)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":719,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[570],"product_cat":[50],"product_tag":[],"class_list":["post-6094","product","type-product","status-publish","has-post-thumbnail","product_brand-repuestos-hyundai","product_cat-partes-electricas","pa_ano-universal","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/product\/6094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/comments?post=6094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/media?parent=6094"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/product_brand?post=6094"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/product_cat?post=6094"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/importacionesflorida.com\/es_es\/wp-json\/wp\/v2\/product_tag?post=6094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}